{"id":258,"date":"2018-03-11T02:53:41","date_gmt":"2018-03-11T01:53:41","guid":{"rendered":"https:\/\/atelier-des-lys.fr\/?page_id=258"},"modified":"2018-03-11T13:27:34","modified_gmt":"2018-03-11T12:27:34","slug":"tapisserie-armoiries-formulaire","status":"publish","type":"page","link":"https:\/\/atelier-des-lys.fr\/index.php\/tapisserie-armoiries-formulaire\/","title":{"rendered":"FORMULAIRE"},"content":{"rendered":"<h5><span style=\"color: #1e73be;\">Int\u00e9r\u00eats pour : <\/span><\/h5>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f21-o1\" lang=\"fr-FR\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/258#wpcf7-f21-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"21\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.5.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f21-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-149\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\" id=\"21\"><span class=\"wpcf7-list-item first\"><span class=\"wpcf7-list-item-label\">Tapisserie<\/span><input type=\"checkbox\" name=\"checkbox-149[]\" value=\"Tapisserie\" \/><\/span><span class=\"wpcf7-list-item last\"><span class=\"wpcf7-list-item-label\">Armoiries<\/span><input type=\"checkbox\" name=\"checkbox-149[]\" value=\"Armoiries\" \/><\/span><\/span><\/span>\n<\/p>\n<p><label> Votre nom (obligatoire)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre adresse de messagerie (obligatoire)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Objet<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Votre message<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control has-spinner wpcf7-submit\" type=\"submit\" value=\"Envoyer\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Int\u00e9r\u00eats pour :<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-258","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/pages\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/comments?post=258"}],"version-history":[{"count":7,"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/pages\/258\/revisions"}],"predecessor-version":[{"id":301,"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/pages\/258\/revisions\/301"}],"wp:attachment":[{"href":"https:\/\/atelier-des-lys.fr\/index.php\/wp-json\/wp\/v2\/media?parent=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}